{"id":8762,"date":"2026-02-19T21:20:03","date_gmt":"2026-02-19T20:20:03","guid":{"rendered":"https:\/\/vanbauseneick.de\/krautnick\/?p=8762"},"modified":"2026-02-19T21:20:03","modified_gmt":"2026-02-19T20:20:03","slug":"kabasse-about-sitting-on-fences-kapitaen-platte-2026","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/kabasse-about-sitting-on-fences-kapitaen-platte-2026\/","title":{"rendered":"Kabasse \u2013 About Sitting On Fences \u2013 Kapit\u00e4n Platte 2026"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2026\/02\/Kabasse-About-Sitting-On-Fences.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"112\" height=\"111\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2026\/02\/Kabasse-About-Sitting-On-Fences.jpg\" alt=\"\" class=\"wp-image-8763\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Von Matthias Bosenick (19.02.2026)<br><br>Von Miles Davis bis Les Claypool, von TV-Bigband bis Rage Against The Machine, und alles zu sechst mit klassischem bis Jazz-Instrumentarium: Was die zwischen Augsburg und M\u00fcnchen angesiedelte Band Kabasse auf ihrem Deb\u00fctalbum \u201eAbout Sitting On Fences\u201c zusammenr\u00fchrt, r\u00fchrt an, denn die Musiker locken erstmal mit vertrauten Jazz-Kl\u00e4ngen und \u00fcberrumpeln mit allerlei anderen Einfl\u00fcssen, von kontemplativ bis zum Mith\u00fcpfen. Die f\u00fcnf instrumentalen Tracks schlagen mehr Haken, als man erfassen kann.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Erstmal w\u00e4hnt man sich in einem Jazz, den man von Miles Davis kennen k\u00f6nnte, so still und entspannt wie zwischen \u201eKind Of Blue\u201c und \u201eIn A Silent Way\u201c, z\u00f6gerliches Schlagzeug, ruhige, behutsame weitere Tasten-, Blas- und Stabspiel-Instrumente, die die H\u00f6rerschaft behutsam an die Hand nehmen, durch die Pforte im Zaun f\u00fchren \u2013 und dann allm\u00e4hlich emporwirbeln. Inmitten eines Orkans errichtet die Band etwas Festes, etwas klar Erkennbares, wie eine riesige, solide Holzkiste, die sichtbar wird, sobald ein Tornado vorbeigezogen ist, funktional, kompakt, ansprechend ausgestaltet, bis alles zusammenbricht und zu einer Art kontemplativen Posaunenchor-Zusammenspiels wird.<br><br>Klingt wild? Das war nur der Einstand, mit dem die Band diverse potentiell m\u00f6gliche Ausrichtungen absteckt. Denn zu Beginn von \u201eIn The Woods\u201c verf\u00e4llt das Sextett ins Experimentieren, ins Klimpern und Klickern, wiederum gechillt. Daraus sch\u00e4lt sich erst allm\u00e4hlich wieder ein Miles-Davis-Jazz der Sechziger hervor. Und dann: beinahe Orchestermusik, ein l\u00e4ssiger Swing, eine Bigband im punktgenauen Stop And Go, eine schw\u00fcle Late-Night-Bar, und alles warm und seelentr\u00f6stend.<br><br>Da sind wir nun erst auf der Schwelle zum dritten Track \u201eHeavy Cloud\u201c, der seinen Titel mit Recht tr\u00e4gt: Hier pumpt die Band ihre Musik zu einem effektvollen Funk mit fettem Schlagzeug auf, so schmissig, dass man sich ihn von Rage Against The Machine gecovert w\u00fcnscht. Kabasse durchsetzen den Track mit experimentellen Jazzpassagen; \u00fcberhaupt punktet bei der Band das Zusammenspiel aus Stabspielen und Blasinstrumenten, die sich harmonisch erg\u00e4nzen. Das folgende \u201eEncore\u201c ist noch nicht die Zugabe, sondern ein stilleres Interludium, das auf das finale \u201eManything Goes\u201c vorbereitet, das beschwingt und nicht plakativ gute Laune verbreitet, manchmal klingt wie TV-Entertainment, mal wie Filmmusik aus einem Krimi-Klassiker, dann pl\u00f6tzlich ein Basssolo liefert mit Les-Claypool-Frickelei, dann in polyrhythmischen Fusion-Funk-Jazz umschwenkt, um Rage Against The Machine kurz zu reaktivieren, mit denen es in einen Lalo-Schifrin-Groove \u00fcbergeht und gef\u00fchlt mittendrin einfach endet.<br><br>Gr\u00fcnder dieser Band ist Sigmund Perner, der hier das Fender Rhodes sowie die Stabspielinstrumente bedient und seinen Sohn Jonas ans Schlagzeug setzt. Mit im Studio waren Bassist Giuseppe Puzzo, Jan Kiesewetter mit Saxophon und Bassklarinette, Martin Lehmann mit Fl\u00fcgelhorn und Trompete sowie Benjamin H\u00e4u\u00dfler mit der Posaune. Die meisten von ihnen sind auch in anderen Gruppierungen aktiv, darunter auch Bigbands, was Wunder, ebenso als Krautrocker, psychedelische Progrocker und Jazzer. Weite Teile von \u201eAbout Sitting On Fences\u201c entstanden laut Info improvisiert, und abermals muss man festhalten, wie komponiert Improvisationen erscheinen, sobald man sie Fachleuten \u00fcberl\u00e4sst. \u00dcber die Kabasse nun l\u00e4sst sich spekulieren: Ist damit ein Synonym f\u00fcr eine Kalebasse gemeint oder die k\u00f6lsche geflochtene Strohtasche Kaba\u00df? Egal: Man sitzt auf dem Zaun und verfolgt das Geschehen, eine Menge zu erleben gibt es allemal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Matthias Bosenick (19.02.2026) Von Miles Davis bis Les Claypool, von TV-Bigband bis Rage Against The Machine, und alles zu sechst mit klassischem bis Jazz-Instrumentarium: Was die zwischen Augsburg und M\u00fcnchen angesiedelte Band Kabasse auf ihrem Deb\u00fctalbum \u201eAbout Sitting On &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/kabasse-about-sitting-on-fences-kapitaen-platte-2026\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8762","post","type-post","status-publish","format-standard","hentry","category-album"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/8762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=8762"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/8762\/revisions"}],"predecessor-version":[{"id":8764,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/8762\/revisions\/8764"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=8762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=8762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=8762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}