{"id":8276,"date":"2025-10-08T21:15:36","date_gmt":"2025-10-08T19:15:36","guid":{"rendered":"https:\/\/vanbauseneick.de\/krautnick\/?p=8276"},"modified":"2025-10-08T21:15:36","modified_gmt":"2025-10-08T19:15:36","slug":"wishes-on-a-plane-lost-songs-old-kids-records-rufen-publishings-new-knee-records-time-as-a-color-2025","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/wishes-on-a-plane-lost-songs-old-kids-records-rufen-publishings-new-knee-records-time-as-a-color-2025\/","title":{"rendered":"Wishes On A Plane \u2013 Lost Songs \u2013 Old Kids Records\/Rufen Publishings\/New Knee Records\/Time As A Color 2025"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2025\/10\/Wishes-On-A-Plane-Lost-Songs.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2025\/10\/Wishes-On-A-Plane-Lost-Songs.jpg\" alt=\"\" class=\"wp-image-8277\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Von Matthias Bosenick (08.10.2025)<br><br>Im Emo-Schubfach verortete sich das M\u00fcnchener Quartett Wishes On A Plane, doch f\u00fchrt dieses Etikett etwas an dem vorbei, was es auf \u201eLost Songs\u201c zu h\u00f6ren gibt, einer Sammlung von Rarit\u00e4ten und Unver\u00f6ffentlichtem, die die Band nun quasi posthum nachreicht. Melancholischer Post-Hardcore, k\u00f6nnte man sagen, keineswegs so jammerig, wie man sich langl\u00e4ufig den Emo vorstellt. Eher Indierock, dazu Akustik-Demos, auf jeden Fall kein Gitarren-Tr\u00fcbsal aus der Kinderperspektive mit verlaufenem Kajal.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a> Auch wenn die Band erst in den Nullern auf den Plan trat, orientierte sie sich deutlich vernehmbar an alternativer Musik aus den Neunzigern. Mit dem mehrstimmigen, leicht psychedelischen, aber klaren Gesang erinnern Wishes On A Plane etwa an die Stone Roses, w\u00e4hrend die Musik dazu im Noiserock, im US-Post-Hardcore oder im Indierock angesiedelt ist. Die Melancholie, die \u00fcber allen Songs liegt, kippt nie ins Deprimierende, erstrecht nicht ins Jammern; sie ist die Decke, unter der sich die Musik ausstreckt und nach dem Restlicht in der Welt Ausschau h\u00e4lt.<br><br>Diese Songsammlung kommt als LP heraus. Die A-Seite beinhaltet drei Songs, die es auf drei rare lokale, also vermutlich im Raum M\u00fcnchen ver\u00f6ffentlichte, Compilations schafften. \u201eUntitled\u201c ist ein noisy, schrammeliger, beseelter Indie-Rock, die Band Wheat schimmert hier erstmals durch. \u201eTide\u201c hat ein wirbelndes H\u00fcsker-D\u00fc-Schlagzeug, und dieser Blick in Richtung Post-Hardcore wird in \u201eWhat\u2019s Left Of What Is \u2026\u201c noch klarer. Jenes St\u00fcck wechselt fortw\u00e4hrend die Intensit\u00e4t, von dezent zu Rock\u2019n\u2019Roll, man k\u00f6nnte es von der Komposition her beinahe f\u00fcr progressiv halten.<br><br>Die B-Seite beginnt mit der \u201eGoldfish Version\u201c als einer fetteren Rock-Variante von \u201eAnywhere\u201c, das 2003 auf der selbstbetitelten Deb\u00fct-EP erschien. Danach folgen drei Akustik-Demos, die offenbar teilweise gar nicht weiter ausgearbeitet wurden. \u201eYesterday\u2019s Another Day\u201c k\u00f6nnte glatt als franz\u00f6sischer Chanson durchgehen, \u201eA Story Called Love\u201c und \u201eNew Year\u2019s Eve\u201c \u2013 letzteres gab\u2019s auch auf der Deb\u00fct-EP \u2013 tragen bereits das in sich, was Daniel Becker heute als Amid The Old Wounds an Solo-Singer-Songwriter-Emo ver\u00f6ffentlicht.<br><br>Die letzte Ver\u00f6ffentlichung von Wishes On A Plane, das irref\u00fchrend betitelte \u201eUnreleased\u201c, erschien 2020, seitdem geht das Quartett getrennte Wege. Neben Becker geh\u00f6rten dazu Anna, Paul Meyer und Tobi, andere Quellen nennen Andreas Gebauer, Paul Meyer und Josef Westermayr. Gut, dass Becker diese \u201eLost Songs\u201c zug\u00e4nglich macht: Es w\u00e4re schade drum gewesen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Matthias Bosenick (08.10.2025) Im Emo-Schubfach verortete sich das M\u00fcnchener Quartett Wishes On A Plane, doch f\u00fchrt dieses Etikett etwas an dem vorbei, was es auf \u201eLost Songs\u201c zu h\u00f6ren gibt, einer Sammlung von Rarit\u00e4ten und Unver\u00f6ffentlichtem, die die Band &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/wishes-on-a-plane-lost-songs-old-kids-records-rufen-publishings-new-knee-records-time-as-a-color-2025\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,16],"tags":[],"class_list":["post-8276","post","type-post","status-publish","format-standard","hentry","category-compilation","category-vinyl"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/8276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=8276"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/8276\/revisions"}],"predecessor-version":[{"id":8278,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/8276\/revisions\/8278"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=8276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=8276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=8276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}