{"id":7534,"date":"2025-04-10T21:08:17","date_gmt":"2025-04-10T19:08:17","guid":{"rendered":"https:\/\/vanbauseneick.de\/krautnick\/?p=7534"},"modified":"2025-04-10T21:08:17","modified_gmt":"2025-04-10T19:08:17","slug":"the-sandmen-hvis-jeg-nogensinde-dor-500-records-2025","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/the-sandmen-hvis-jeg-nogensinde-dor-500-records-2025\/","title":{"rendered":"The Sandmen \u2013 Hvis jeg nogensinde d\u00f8r \u2013 500% Records 2025"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2025\/04\/The-Sandmen-Hvis-jeg-nogensinde-dor.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2025\/04\/The-Sandmen-Hvis-jeg-nogensinde-dor.jpg\" alt=\"\" class=\"wp-image-7535\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Von Matthias Bosenick (10.04.2025)<br><br>\u201eH\u00f6r zu und verlieb dich\u201c, steht bei Spotify, wenn man nach \u201eHvis Jeg Nogensinde D\u00f8r\u201c sucht, dem neuen Album von The Sandmen, einer der d\u00e4nischen Rock-Institutionen. Man sollte es aber trotzdem lieber auf Vinyl erwerben! Dies d\u00fcrfte das zehnte Album in 40 Jahren sein, ganz sicher das f\u00fcnfte seit der Reunion und das dritte auf D\u00e4nisch statt Englisch. Es setzt den neuen Weg fort, den klassischen Bluesrock zu modernisieren, ihm melancholische Noten zu verleihen, auf gew\u00f6hnliche Strukturen zu verzichten und einfach zu machen, worauf die Band Bock hat. Das h\u00f6rt man und das kommt genau richtig. Zum Beispiel mit Synthies und Saxophon.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a> Als Blues mit synthetischen Drums und Mundharmonika beginnt der erste Song, \u201eVed du hvem jeg er\u201c. Das St\u00fcck l\u00e4sst sich sieben Minuten Zeit, um sich aufzubauen, um einen hypnotischen Sog zu entwickeln, um die Musik zu intensivieren, dem Drumcomputer einen echten Schlagzeuger an die Seite zu stellen etwa, und dazu immer wieder zu fragen: \u201eWei\u00dft du, wer ich bin?\u201c Klar: The Sandmen, 1985 in Kopenhagen gegr\u00fcndet, 1987 mit einem Mini-Album gestartet, 1988 in D\u00e4nemark, 1989 in den USA mit \u201eWestern Blood\u201c auf Albuml\u00e4nge auf sich aufmerksam gemacht, 1991 mit dem \u00fcbern\u00e4chsten Album \u201eSleepyhead\u201c und dem Riesenhit \u201eFive Minutes Past Loneliness\u201c auf Augenh\u00f6he mit den Cowboyrock-Landsleuten D-A-D ins Bewusstsein der H\u00f6rerschaft gespielt, nach dem Nachfolgealbum \u201eIn The House Of Secrets\u201c Mitte der Neunziger getrennt und 2006 mit \u201eWhite Trash Red Front\u201c und einem \u00fcberraschend neuen Sound reaktiviert. Der tanzbare Indierock der Nuller hatte Einfluss auf den neuen Sound, der sich in \u201eShine\u201c 2008 fortsetzte und zu einer weiteren Unterbrechung f\u00fchrte. Aus der die Band 2014 mit \u201eDen bedste dag\u201c deutlich abgedunkelt und mit neuem Elan hervorging, der hoffentlich noch lang anh\u00e4lt. Damit geh\u00f6ren The Sandmen in die sehr kurze Liste der Bands, die nach einer Reunion relevante neue Alben ver\u00f6ffentlichten.<br><br>Zu denen geh\u00f6rt auch das neue, und auf Position zwei folgt das Titellied \u201eHvis jeg nogensinde d\u00f8r\u201c, also \u201eWenn ich jemals sterbe\u201c. Das beginnt reduziert mit Akustikgitarre und dem Sound einer Hammond-Orgel, geht dann pl\u00f6tzlich in einen waschechten 1990er-Madchester-Rhythmus \u00fcber und endet als Indierock-Kopfnicker mit begleitenden Synthiefl\u00e4chen. Noch mehr auf die Tanzfl\u00e4che dr\u00fcckt \u201eSparker til det hele\u201c, ungef\u00e4hr \u201eAuf die Tube dr\u00fccken\u201c, also \u201eBeschleunigen\u201c, und genau das macht der Song, mit zum Zappeln einladenden Shakern, Synthies zum Rock und m\u00e4chtigem Groove. Zuletzt begleitet ein Frauenchor kurz den Hauptgesang und das Saxophonsolo.<br><br>Auf der B-Seite erinnert der Titel \u201eGi mig gi mig\u201c an das offizielle Deb\u00fct \u201eGimme Gimme\u201c, der Song selbst nur so halb: Bluesrock ja, amtliches Gegniedel ebenso, aber hier leicht synthetisch unterf\u00fcttert, also ein Bisschen wie ZZ Top in den Achtzigern, aber so dreckig wie ZZ Top in den Siebzigern. Plus Saxophon am Ende. Anschlie\u00dfend wird die Band \u201eAben\u201c, \u201eOffen\u201c, f\u00fcr mehr Tempo. Dieses ist der schnellste Song des Albums, bleibt zun\u00e4chst im Bluesschema, bekommt abermals einen milderen Refrain mit melodischer Synthieunterst\u00fctzung, ohne abzubremsen, und verwechselt \u00fcber Spielzeit auch nicht Tempo mit H\u00e4rte, auch wenn er rockt \u2013 Energie verspr\u00fcht der Song trotzdem m\u00e4chtig. Zum Abschluss gibt\u2018s mit \u201eSvaneflugt\u201c, \u201eSchwanenflug\u201c, eine Ballade. Die beginnt so vertraut, dass man noch denkt: Huch, wie banal! Und dann steigert sich die Band hinein, intensiviert das Spiel, beginnt zu gniedeln, singt wie beim Gospel, f\u00e4hrt alle Regler hoch und fuzzt, mostet, dronet den Song ins folkig gefl\u00f6tete Chill-Out-Finale.<br><br>Sechs Songs, 33 Minuten, man k\u00f6nnte entt\u00e4uscht sein, wenn man rein nach Statistik geht, aber das tun nur H\u00f6rer ohne Seele, denn die bekommt hier ihre Streicheleinheiten. Das Melancholische der Vorg\u00e4ngeralben sch\u00fcttelt die Band gl\u00fccklicherweise nicht vollst\u00e4ndig ab, pr\u00e4gt aber jeden einzelnen der sechs neuen Songs mit einem eigenen Charakter aus, der diese Melancholie unterschiedlich stark transportiert. Das geht auch, w\u00e4hrend man ausgelassen tanzt oder den Kopf zum Bluesrock sch\u00fcttelt. Wie gut, dass diese Band ihrem Bestehen neue Chancen gab \u2013 es w\u00e4re der Welt etwas entgangen.<br><br>Seit 40 Jahren dabei sind nur noch zwei: S\u00e4nger Allan Vegenfeldt und Schlagzeuger Michael Illo Rasmussen. Gitarrist Stefan Moulvard ist seit der Reunion in den Nullern fester Bestandteil der Band, also auch schon ungef\u00e4hr deren halbe Existenz lang; er war bereits Teil von Nerve, der Band, die einige Sandm\u00e4nner nach dem Split in den Neunzigern gegr\u00fcndet hatten. Als fester Leih-Bassist ist Jens Hein seit der 2917er Record-Store-Day-Single \u201eAlle fangerne\u201c zu h\u00f6ren, einem Cover der Punkband Before, in der Rasmussen vor The Sandmen trommelte. G\u00e4ste sind auf \u201eHvis jeg nogensinde d\u00f8r\u201c noch der Bluesgitarrist und Mundharmonikaspieler Jarno Varsted sowie Saxophonist Ned Ferm.<br><br>Zwar gibt es \u201eHvis jeg nogensinde d\u00f8r\u201c auch auf CD, aber seit die Band auf D\u00e4nisch singt, sind auch die Vinyl-Varianten der Alben von gro\u00dfem Interesse. Dieses hier gibt es in so vielen verschiedenen Farben und Melangen, dass man gar nicht wei\u00df, welche man am liebsten auf seinen Plattenteller legen w\u00fcrde. Des Rezensenten w\u00e4rmster Dank geht da an Band-Promoter Ronnie Bj\u00f8rn H\u00f8egh, der f\u00fcr ihn eine vortreffliche Auswahl traf!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Matthias Bosenick (10.04.2025) \u201eH\u00f6r zu und verlieb dich\u201c, steht bei Spotify, wenn man nach \u201eHvis Jeg Nogensinde D\u00f8r\u201c sucht, dem neuen Album von The Sandmen, einer der d\u00e4nischen Rock-Institutionen. Man sollte es aber trotzdem lieber auf Vinyl erwerben! Dies &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/the-sandmen-hvis-jeg-nogensinde-dor-500-records-2025\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,16],"tags":[],"class_list":["post-7534","post","type-post","status-publish","format-standard","hentry","category-album","category-vinyl"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=7534"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7534\/revisions"}],"predecessor-version":[{"id":7536,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7534\/revisions\/7536"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=7534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=7534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=7534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}