{"id":7528,"date":"2025-04-09T21:56:28","date_gmt":"2025-04-09T19:56:28","guid":{"rendered":"https:\/\/vanbauseneick.de\/krautnick\/?p=7528"},"modified":"2025-04-09T21:56:28","modified_gmt":"2025-04-09T19:56:28","slug":"sendelica-the-complete-mankind-fruits-de-mer-records-2025","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/sendelica-the-complete-mankind-fruits-de-mer-records-2025\/","title":{"rendered":"Sendelica \u2013 The Complete Mankind \u2013 Fruits De Mer Records 2025"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2025\/04\/Sendelica-The-Complete-Mankind.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"130\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2025\/04\/Sendelica-The-Complete-Mankind.jpg\" alt=\"\" class=\"wp-image-7529\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Von Matthias Bosenick (09.04.2025)<br><br>Vom Neanderthaler bis zum Tod: Die Entwicklung der Menschheit bis hin in die Unendlichkeit steht als Thema \u00fcber den vier Teilen der \u201eMankind\u201c-Trilogie, die das progressive Psychedelic-Space-Kraut-Rock-Trio Sendelica aus Wales in den zur\u00fcckliegenden vier Jahren auf vier Doppel-LPs bearbeitete. F\u00fcr CD-Sammler gibt\u2019s jetzt die Variante als Box mit acht CDs, n\u00e4mlich die vier Alben plus je einer Erg\u00e4nzungs-Compilation mit Outtakes, Mixes, Demos und Alternativversionen. Macht neuneinviertel Stunden Abtauchen, von der Ursuppe ins All.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Zuerst die harten Fakten: \u201eThe Complete Mankind\u201c bietet 9:15 Stunden Musik in 51 Tracks, der k\u00fcrzeste, \u201e120 BPM Riff Idea Two\u201c, dauert 0:42 Minuten, \u201eCosmic Slop (In The Beginning) Let There Be Light\u201c als l\u00e4ngster 22:56 Minuten, die Durchschnittsl\u00e4nge liegt bei gut zehn Minuten. Die Original-Doppel-LPs waren \u201eAnd Man Created God\u201c (2021), \u201eOne Man&#8217;s Man\u201c (2022), \u201eMan, Myth And Magic\u201c (2023) sowie als vierter Teil der urspr\u00fcnglichen Trilogie \u201eRequiem For Mankind\u201c (2024), letzteres bereits bei KrautNick besprochen und jedes mit einer unterscheidbaren musikalischen Grundausrichtung. Mit acht CDs ist diese Box noch \u00fcppiger als \u201eThe Compleat Chromlech Chronicles\u201c, die 2020 die vier \u201eChromlech Chronicles\u201c plus einem Live-Album und einem Bonus-Album sowie vereinzelten Bonus-Tracks auf den jeweiligen Alben vereinten. Inhaltlich befasste sich die Band bei der \u201eMankind\u201c-Reihe nun mit Religionen, konkreter den Parallelen zwischen Sumerern und der Bibel und somit der Herkunft des Menschen und dessen m\u00f6glichem Verbleib.<br><br>Ein weiterer harter Fakt ist, dass es auf den vier Original-Alben keine kompakten Tracks gibt, die man mal eben ins Radioprogramm streuen k\u00f6nnte, obwohl manche von ihnen kompositorisch und strukturell das Zeug dazu h\u00e4tten, insbesondere diejenigen mit dem gr\u00f6\u00dferen Achtziger-Artrock-Sound. Hei\u00dft: Unter sechs Minuten dauert keiner der Album-Tracks, denn in denen verliert sich die Band aufs Epischste, wie es sich f\u00fcr diese Richtung geh\u00f6rt. Dabei hat die Band nicht nur keine Angst vor Synthies, sondern setzt sie mit Vorliebe charakteristisch ein, bisweilen sogar Samples, Field Recordings oder Scratches, etwa in \u201eHomo Erectus\u201c. Au\u00dferdem l\u00e4sst das Trio neben Gitarre, Bass und Schlagzeug auch G\u00e4ste ins Studio, die ihr Saxophon oder ihr Cello gewinnbringend einbringen. Texte gibt es keine, Stimmen hingegen schon, in ausgew\u00e4hlten St\u00fccken. Manche der Alternativmixe verleihen den Originalen einen Zugewinn, andere gar eine v\u00f6llig neue Dimension; noch ein Fakt ist, dass diese Sammlung die angenehm berauschende Kontemplationszeit verdoppelt.<br><br>Der Beginn der Menschheit verl\u00e4uft nicht ganz reibungslos: Im Intro knarzt \u201eAeolian Sunrise\u201c gewaltig, erst dann startet das St\u00fcck mit orientalischen Percussions und Drones. So wechselvoll wie die Geschichte der Menschheit ist auch die Musik, die man ab jetzt vor sich hat. Verteilt auf die Tracks bedienen sich Sendelica diverser Vorgehensweisen: Manche Tracks scheinen auf Wiederholung zu basieren, auf einer Art Loop, \u00fcber die sich die eigentliche Musik legt wie eine Kuscheldecke. Andere erscheinen wie durchgespielte epische Tracks, in denen sich die Musizierenden so verlieren, wie es die H\u00f6renden dann ebenfalls vollf\u00fchren. Manche tragen eine Pink-Floyd-Taubheit in sich, manche eine Neil-Young-Gniedel-Versunkenheit, etwa \u201eMMT\u201c, das ohnehin sehr an \u201eLike A Hurricane\u201c erinnert, ebenso die Skizze \u201e120 BPM Riff Idea One\u201c.<br><br>Jenes St\u00fcck geh\u00f6rt mit dem eingebauten Saxophon in der Bonus-Sektion auch zu denen mit ordentlich Mehrwert, nebenbei. Ebenso \u201eSurging Forde\u201c, das mit seinen Electro-Effekten an Kraftwerk erinnert, oder manche Demos zum zweiten und vierten Album, die zum Drumcomputer entstanden. Synthies spielen ja ohnehin eine nicht unwichtige Rolle bei Sendelica, so kann einer auch mal nach Marillion klingen oder wie im Intro zu \u201eIlluminated Skies\u201c nach Foreigner. Daf\u00fcr hat der Basslauf in jenem Track etwas von der NWoBHM, ohne dass die Band jemals in Richtung Metal geht, obschon das zweite Album recht rockig ausf\u00e4llt. \u201eHomo Rudolfenis\u201c etwa m\u00f6chte zwischen \u201eSilver Machine\u201c von Hawkwind und \u201eBorn To Be Wild\u201c von Steppenwolf einsortiert werden. Mit der Gitarre l\u00e4sst sich ja auch Anderes anstellen: Man kann mit ihr gniedeln, sie durch den Wahwah jagen, sie wie in \u201eThe Seekers\u201c nach Walgesang klingen lassen, sie als dronige Fl\u00e4che einsetzen, mit ihr wie in \u201eTower Of Chaos\u201c abstrakt-avantgardistisch herumexperimentieren, oder sie als Erg\u00e4nzung zu dem Groove sehen, den Bass und Schlagzeug bisweilen errichten. Nicht nur Groove, auch mal eine weite Strecke, wie auf der dritten, dem Krautrock nahen Platte, auf der die typischen D\u00fcsseldorfer stoischen Beats voranschreiten. Oder auch mal aussetzen, wie in \u201eEpilogue Sunset\u201c oder dem \u201eOriginal Pete \u201aYeti\u2018 Mix\u201c von \u201eHomo Erectus\u201c, die lediglich der S\u00e4gegitarre und einem blubbernden Synthie Raum bieten.<br><br>Synthiegenerierter Ambient \u2013 in \u201eMagician Dawn\u201c sogar in Richtung Neo-Klassik gehend \u2013 ist ohnehin ein regelm\u00e4\u00dfiger Bestandteil der Sendelica-Musik, nicht nur im Bonus-Teil des zweiten Albums, denn irgendwie muss die Mucke ja spacig werden, wenn man nicht gerade Gitarren exzessiv verfremdet. Hall und Echo d\u00fcrfen auch mal zum Einsatz kommen, das \u00e4therische Saxophon hat seinen zus\u00e4tzlichen Anteil am Entr\u00fcckten, im energetischen \u201eWheel Of Fortune\u201c darf es sogar kakophonisch werden. So entsteht einerseits eine unfassbare Sch\u00f6nheit, andererseits auch pure Psychedelik oder abstrakter, jazziger Rock, also Musik zwischen verstiegen und verstrahlt, harmonisch und goovend, und das zum Teil sogar innerhalb der schier unendlich langen Tracks. Auch etwas flotter darf\u2018s mal werden, \u201eHomo Sapien\u201c etwa ist eine Art Speed-Chill-Out.<br><br>Den Kern der Band Sendelica bildet ein Trio: Peter Bingham spielt alle erdenklichen Gitarren sowie Synthies und Sampler, Colin Consterdine \u00fcbernimmt Schlagzeug und Electro-Anteile und Glenda Pescado den Bass. So oft, wie das Saxophon hier wesentliche Anteile einnimmt, k\u00f6nnte man Lee Relfe als viertes Bandmitglied auffassen; dieser umtriebige Mensch spielte auch mal bei den Italienern Da Captain Trips das Sax. Ab dem zweiten Doppelalbum ist Santtu Laakso mit Moogs und anderen Synthies wiederkehrender Gast. Rhiannon Jones tr\u00e4gt Cello bei, Stimmen gibt\u2019s von Elfin Bow alias Elizabeth Anne Jones und jemandem namens Calli, alles jeweils einmalig, obschon letztere zweimal auftaucht, weil das verz\u00fcckende \u201eCalli Vocal Demo\u201c ihres Songs \u201eRequiem for The Planet\u201c als Bonus enthalten ist.<br><br>Bei dem Aussto\u00df, den die Musizierenden bereits als Sendelica haben, wundert es, dass sie alle noch in unendlichen anderen Projekten arbeiten. Am kuriosesten d\u00fcrfte A.B.B.A. sein \u2013 unter diesem Namen covern sie Gruftklassiker in psychedelisch. Passt ja, schlie\u00dflich spielten sie ja aus der gleichen Zeit als Sendelica schon mal \u201eI Feel Love\u201c von Donna Summer neu ein. Einen weiten Horizont muss man nur haben, und den h\u00f6rt man dieser \u201eMankind\u201c-Box unbestreitbar an.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Matthias Bosenick (09.04.2025) Vom Neanderthaler bis zum Tod: Die Entwicklung der Menschheit bis hin in die Unendlichkeit steht als Thema \u00fcber den vier Teilen der \u201eMankind\u201c-Trilogie, die das progressive Psychedelic-Space-Kraut-Rock-Trio Sendelica aus Wales in den zur\u00fcckliegenden vier Jahren auf &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/sendelica-the-complete-mankind-fruits-de-mer-records-2025\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-7528","post","type-post","status-publish","format-standard","hentry","category-box"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=7528"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7528\/revisions"}],"predecessor-version":[{"id":7530,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7528\/revisions\/7530"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=7528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=7528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=7528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}