{"id":7090,"date":"2024-12-16T21:59:58","date_gmt":"2024-12-16T20:59:58","guid":{"rendered":"https:\/\/vanbauseneick.de\/krautnick\/?p=7090"},"modified":"2024-12-17T20:44:18","modified_gmt":"2024-12-17T19:44:18","slug":"the-twang-western-wonderland-live-am-14-12-2024-brunsviga-braunschweig","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/the-twang-western-wonderland-live-am-14-12-2024-brunsviga-braunschweig\/","title":{"rendered":"The Twang \u2013 Western Wonderland \u2013 Live am 14.12.2024, Brunsviga, Braunschweig"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"912\" data-id=\"7091\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank-1024x912.jpg\" alt=\"\" class=\"wp-image-7091\" srcset=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank-1024x912.jpg 1024w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank-300x267.jpg 300w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank-768x684.jpg 768w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank-1536x1368.jpg 1536w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank-337x300.jpg 337w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Hank.jpg 1667w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"451\" data-id=\"7094\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-1024x451.jpg\" alt=\"\" class=\"wp-image-7094\" srcset=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-1024x451.jpg 1024w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-300x132.jpg 300w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-768x338.jpg 768w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-1536x677.jpg 1536w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-2048x902.jpg 2048w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang-500x220.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1022\" height=\"1024\" data-id=\"7095\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-1022x1024.jpg\" alt=\"\" class=\"wp-image-7095\" srcset=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-1022x1024.jpg 1022w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-300x300.jpg 300w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-150x150.jpg 150w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-768x770.jpg 768w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-1533x1536.jpg 1533w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-2043x2048.jpg 2043w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_Hank_Randy-299x300.jpg 299w\" sizes=\"auto, (max-width: 1022px) 100vw, 1022px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_mit_Pyrotechnik-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"836\" height=\"1024\" data-id=\"7096\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_mit_Pyrotechnik-836x1024.jpg\" alt=\"\" class=\"wp-image-7096\" srcset=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_mit_Pyrotechnik-836x1024.jpg 836w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_mit_Pyrotechnik-245x300.jpg 245w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_mit_Pyrotechnik-768x941.jpg 768w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_mit_Pyrotechnik-1254x1536.jpg 1254w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Marshall_mit_Pyrotechnik-1672x2048.jpg 1672w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"798\" data-id=\"7092\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke-1024x798.jpg\" alt=\"\" class=\"wp-image-7092\" srcset=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke-1024x798.jpg 1024w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke-300x234.jpg 300w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke-768x599.jpg 768w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke-1536x1198.jpg 1536w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke-2048x1597.jpg 2048w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-Winke_winke-385x300.jpg 385w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"7093\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-1024x578.jpg\" alt=\"\" class=\"wp-image-7093\" srcset=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-1024x578.jpg 1024w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-300x169.jpg 300w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-768x433.jpg 768w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-1536x866.jpg 1536w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-2048x1155.jpg 2048w, https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/12\/Guido-Twang-The_Twang_mit_Weihnachtsbaum-500x282.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Von Guido D\u00f6rheide (15.12.2024)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bereits zum 26. Mal laden The Twang heuer zu ihrer Country- und Western-Weihnachtsveranstaltung ein und wie zu erwarten m\u00fcssen Hank Twang (voc), Marshall Twang (git), Randy Twang (b), Rusty Twang (dr), Beano Van Twang (git), \u201eDer namenlose Karsten Twang\u201c (an der Pedal Steel und der Trompete \u2013 aber eigentlich ist Karsten doch ein Name, oder, Carsten?) und der Reverend (git, voc) nicht lange bitten \u2013 das Event ist bereits seit Oktober ausverkauft. Dank meines Kollegen Micha (ihn ihm sein richtiger Name ist der Redaktion bekannt) komme ich noch wenige Tage vor dem Ereignis (Occurrence, gell, Micha?) in den Genuss, zwei der l\u00e4ngst nicht mehr zu kriegenden Karten zu erstehen: Dem Kollegen, nennen wir ihn der Einfachheit Micha, und seiner Liebsten kam was dazwischen, meine Liebste musste arbeiten, und so \u00fcbernehmen Freund&amp;Kollege Carsten und ich die beiden Karten, und was soll ich sagen? Wir amis\u00fcren uns pr\u00e4chtig.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Zun\u00e4chst einmal sorgen wir f\u00fcr das gastrologische Wohl und gehen lecker essen \u2013 das ansonsten \u00fcber jeden Zweifel erhabene Restaurant ist aber Dank der obwaltenden Weihnachtsfeiersaison sowas von mit G\u00e4sten angef\u00fcllt, dass a) Bestellen, b) Essen und c) Bezahlen deutlich mehr Zeit in Anspruch nehmen als geplant, und so st\u00fcrzen wir erst Punkt 8 Uhr in die Brunsviga, schmei\u00dfen unsere Winterjacken auf die Garderobe und betreten den verdammt gut gef\u00fcllten Saal genau in dem Moment, in dem Hank Twang die Frage an das Auditorium richtet, ob es denn auch artig gewesen sei. Frage bejaht und The Twang legen mit einem amerikanischen Weihnachtslied los. Hank tr\u00e4gt zu diesem Behufe neben dem \u00fcblichen an den Seiten hochgebogenen Cowboyhut einen knallroten Anzug, von dem er sp\u00e4ter versichert, er sei aus Polyester und nicht eben atmungsaktiv, weshalb er einen Deal mit einer \u00f6rtlichen Autowaschanlage habe und des \u00d6fteren mit dem Anzug und ausgebreiteten Armen durch diese hindurchlaufen d\u00fcrfe, was zun\u00e4chst gew\u00f6hnungsbed\u00fcrftig, aber im Endeffekt hilfreich w\u00e4re. Schwamm dr\u00fcber, der Anzug putzt auf jeden Fall ungemein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um die Zuh\u00f6renden nicht vergessen zu lassen, dass sie sich inmitten einer Weihnachtsveranstaltung befinden, fragt Hank gleich relativ zu Anfang die Namen von Santa Claus\u2019 Rentieren ab. Blitzen war den meisten bekannt, bei Dasher, Dancer, Prancer, Cupid und Vixen wurde es dann schon schwieriger, und am Ende enth\u00fcllte der Reverend, dass es auch ein Rentier namens Nixon gegeben h\u00e4tte. Dieses sei allerdings schon in den fr\u00fchen 70er Jahren von seinem Amt zur\u00fcckgetreten. \u00dcberhaupt der Reverend: Seine permanente Interaktion mit Hank ist es, die das Western Wonderland neben der dargebotenen wunderbaren und \u00fcber jeden verdammten Zweifel erhabenen Country-Musik zu etwas v\u00f6llig Einzigartigen und Zauberhaften macht: So machen die beiden zum Beispiel gleich zu Anfang Andeutungen, dass es eine Person namens J\u00f6rg g\u00e4be, die einen wichtigen Einfluss auf den Reverend aus\u00fcbe und die der Veranstaltung auch hinter der B\u00fchne beiwohne, in einem Pferdetrailer mit Whirlpool und Pferdetr\u00e4nke. Mehr wird erstmal nicht verraten und stattdessen gibt es Musik. Haufenweise Weihnachtslieder, die mit der Pedal Steel das richtige Ma\u00df an Countryfizierung erfahren (und wenn das nicht reicht, greift der Reverend zum Banjo und der namenlose Karsten zur Mariachi-Trompete), aber auch weltliche Ges\u00e4nge: So zum Beispiel \u201eBlowin\u2019 In The Wind\u201c, kombiniert mit der Musik von \u201eTake Me Home, Country Roads\u201c. Oder auch \u201eAce \u00f6f Spades\u201c, das \u00fcbergangslos in \u201eFeliz Navidad\u201c und dann in \u201eWe Are The World\u201c \u00fcbergeht, um dann wieder bei \u201eAce \u00f6f Spades\u201c zu landen. Oder The Twang beginnen \u201eWalk On The Wild Side\u201c von Lou Reed, machen (innerhalb desselben Songs) weiter mit \u201eI\u2019m Walking\u201c, dann kurz \u201eWithout Me\u201c von Eminem und auf einmal sind wir wieder bei \u201eWalk On The Wild Side\u201c. Wie machen die das?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun \u2013 sie machen es ganz hervorragend. Musikalisch sind The Twang wirklich hochklassig \u2013 sie beherrschen nicht nur beide Musikrichtungen, sondern sind locker in der Lage, egal welchen Song (und wenn ich sage, egal welchen Song, meine ich exakt egal welchen Song) zu countryfizieren, als w\u00e4re er nie einem anderen Genre zuzuordnen gewesen. Und springen dabei selber noch von Genre zu Genre (ohne den Country dabei wirklich zu verlassen), dass einem der Atem stockt: So bekommt zum Beispiel Marshall Twang gegen Ende des Sets die Gelegenheit, seine Heavy-Metal-Vorlieben auszuspielen, und haut dem Auditorium wundervolle harte Riffs und Soli um die Ohren, derweil Hank mittels einer Fernbedienung eine pyrotechnische Apparatur z\u00fcndet, die direkt vor des Marshalls Telecaster einen Funkenregen in die H\u00f6he spr\u00fchen l\u00e4sst, und Marhall Twangs Augen leuchten ob dieses Spectaculums vor geradezu weihnachtlich-kindlicher Freude, soowas Sch\u00f6nes!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Irgendwann wird dann auch das Geheimnis um den geheimnisvollen J\u00f6rg enth\u00fcllt: J\u00f6rg ist ein Shetland Pony, mit dem der Reverend seit einiger Zeit zusammenlebt. Shetland Ponys, so erl\u00e4utert der Reverend, seien eigens daf\u00fcr gez\u00fcchtet worden, in den Minen die Wagen zu ziehen. Shetland Ponys seien also Arbeiterklasse und gewerkschaftlich organisiert. Hank deutet \u2013 wenn auch deutlich vorsichtiger formuliert \u2013 an, dass die Beziehung zwischen J\u00f6rg und dem Reverend leicht toxische Z\u00fcge tr\u00e4gt, was sich dahingehend manifestiert, dass J\u00f6rg und der Reverend gegen Ende der Show ein Telefonat f\u00fchren, in dem der Reverend dem treuen Tier versichert, dass man nun beim vorletzten Song angekommen sei und der Reverend nun bald J\u00f6rg im Pferdetrailer noch einen M\u00f6hrensaft servieren w\u00fcrde. An dieser Stelle wird auch der Vorverkauf f\u00fcr die n\u00e4chste Weihnachtsshow von The Twang er\u00f6ffnet, die den Titel \u201eFairytale Of New J\u00f6rg\u201c tragen werde. Namentliches \u201eFairytale Of New York\u201c wird dann auch zum Besten gegeben \u2013 mein allerallerliebstes Weihnachtslied aller Zeiten von dem unsterblichen zweitgr\u00f6\u00dften Songwriter aller Zeiten, Shane MacGowan. McGowans Rolle wird hier vom Reverend \u00fcbernommen und Hank Twang singt die Zeilen, die im Original von Kirsty MacColl gesungen werden. Mehr Weihnachten geht nicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muss auch nicht, denn The Twang haben noch so viel mehr Musik im K\u00f6cher, die hier auch endlich mal raus muss, und dazu Anekdoten \u00fcber das Leben als Solches und im Wilden Westen im Besonderen. Wie zum Beispiel die Geschichte, die Hank Twang \u00fcber Marshall Twang erz\u00e4hlt: Letzterer war seinerzeit an der Grenze zwischen Texas und Mexiko unterwegs, \u00fcber ihm die Geier und vor ihm die Koyoten, Wasser, Wasser \u00fcberall und kein einziger Tropfen zu trinken. Alsdann begab er sich in eine Bar, dort schauten ihn der Barmann, ein Koyote und zwei Geier an, Marshall verlangte Wasser und bekam zur Antwort, dass eine Dame aus Hagen (bekleidet mit einer Spandex-Hose und dort in der Ecke sitzend) alles Wasser ausgetrunken h\u00e4tte und somit die Anfrage abschl\u00e4gig beschieden werden m\u00fcsse. Hank beginnt mit \u201eDie Dame sagte\u201c und der Reverend vervollst\u00e4ndigt \u201eIch bin total verwiert!\u201c, was Hank zu einem ziemlichen Kicheranfall und der Replik \u201eIch werd\u2019 verr\u00fcckt, wenn\u2019s heut\u2019 passiert\u201c n\u00f6tigt. Und dann spielen The Twang nat\u00fcrlich nicht \u201eNur getr\u00e4umt\u201c, sondern \u201e99 Luftballons\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und so geht es die ganze Zeit zwischen Hank und dem Reverend: Beide bringen sich gegenseitig spontan zum Lachen, hier wirkt nichts einstudiert, sondern spontan rausgehauen, und dazwischen gibt es Musik von einer gro\u00dfartigen Band, die wunderbar aufeinander eingespielt ist, und die es feiert, dem Publikum eine wundersch\u00f6ne Einstimmung auf die Weihnachtszeit zu bieten. Die besser nicht eingel\u00e4utet werden kann. Von J\u00f6rg und einem Hippopotamus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Guido D\u00f6rheide (15.12.2024) Bereits zum 26. Mal laden The Twang heuer zu ihrer Country- und Western-Weihnachtsveranstaltung ein und wie zu erwarten m\u00fcssen Hank Twang (voc), Marshall Twang (git), Randy Twang (b), Rusty Twang (dr), Beano Van Twang (git), \u201eDer &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/the-twang-western-wonderland-live-am-14-12-2024-brunsviga-braunschweig\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-7090","post","type-post","status-publish","format-standard","hentry","category-konzert"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=7090"}],"version-history":[{"count":2,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7090\/revisions"}],"predecessor-version":[{"id":7098,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7090\/revisions\/7098"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=7090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=7090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=7090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}