{"id":7015,"date":"2024-11-27T12:33:35","date_gmt":"2024-11-27T11:33:35","guid":{"rendered":"https:\/\/vanbauseneick.de\/krautnick\/?p=7015"},"modified":"2024-12-10T19:44:41","modified_gmt":"2024-12-10T18:44:41","slug":"sacred-buzz-radio-radiation-ep-fuzzed-up-astromoon-records-2024","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/sacred-buzz-radio-radiation-ep-fuzzed-up-astromoon-records-2024\/","title":{"rendered":"Sacred Buzz \u2013 Radio Radiation EP \u2013 Fuzzed Up\/Astromoon Records 2024"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/11\/Sacred-Buzz-Radio-Radiation-EP.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"https:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/11\/Sacred-Buzz-Radio-Radiation-EP.jpg\" alt=\"\" class=\"wp-image-7016\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Von Matthias Bosenick (27.11.2024)<br><br>Hier ist sie nun also, die angek\u00fcndigte EP zur 7\u201c mit demselben Titel, \u201eRadio Radiation\u201c, des von Berlin aus agierenden Quartetts Sacred Buzz. Die beiden Vinyl-Tracks sind mit drauf, dazu vier neue, die sich allesamt in einer wie in den Sechzigern ausgestatteten Garage wohlf\u00fchlen, mit Verzerrer und mit Orgel, mit Psychedelik und mit fuzzy Rock\u2019n\u2019Roll. Und alles live im Studio eingespielt.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Die beiden Songs der Single, \u201eRadio Radiation\u201c und \u201eRebel Machine\u201c, bilden eine energetische Klammer um diese Songs, als erster und als letzter Track. Dazwischen tobt sich das Quartett wie auf einer Zeitreise aus, kombiniert den in die Sechziger verzerrten Sound der Milchbars mit von Flower Power inspirierten psychedelischen Strukturen, l\u00e4sst den Surf-Twang von der Leine und scheut sich auch nicht davor, mal Ruhe einkehren zu lassen. Dabei tritt die Band das Fuzzpedal nur dezidiert durch, \u00fcbertreibt es also nicht, sondern l\u00e4sst Varianten und Strukturen zu, die das H\u00f6ren zum abwechslungsreichen Genuss machen. H\u00e4ufig bleiben die Saiteninstrumente n\u00e4mlich clean, und wenn dann die Orgel dazu dudelt, m\u00f6chte man sein Sechziger-Surfboard wieder aus der Garage holen.<br><br>Mit den fuzzy Songs verorten sich Sacred Buzz ganz klar im Garage Punk von vor 60 Jahren, aber sie haben eben mehr in petto. Der Popsong \u201eAntihero\u201c bleibt clean, die Gitarre hallt dennoch aus den Sechzigern nach. Mit \u201eRevolution\u201c bringt das Quartett einen Uptempo-Mitsing-Hit unter. \u201eNo Wings\u201c ist eine Ballade, in die die Band ein fuzzy Solo einbaut. \u201eMake It Go Wrong\u201c sticht kompositorisch aus den sechs Songs heraus: Es beginnt mit sanft gepickter Gitarre, einem sch\u00f6nen Drone und harmonischen Sounds mit verschachteltem Schlagzeug, ganz so, als bef\u00e4nde man sich pl\u00f6tzlich im progressiven Fach des Plattenladens. Nach der H\u00e4lfte setzt die Orgel ein \u2013 und die Band drischt los.<br><br>Die Besetzung entspricht nat\u00fcrlich der der Single: Die Gitarre und den verzerrten Gesang liefert Ivan Skvortsov, seine Gattin Jane Skvortsova an den Keyboards steuert mithin die Orgel bei. Bass spielt Luca B\u00fcttner und Schlagzeug Max Storck, auf der 7\u201c noch genannt \u201eDreieckskreis\u201c. Diese noch sehr jung in Berlin zusammengekommene Band \u2013 das erste Demo ist genau ein Jahr alt \u2013 steuert zurzeit den Live-Sprung nach au\u00dferhalb der Stadtgrenzen sowie die Aufnahmen des ersten Albums an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[Edit 28.11.2024] Die Bandcamp-Version der EP enth\u00e4lt als Bonus den \u00fcber 21 Minuten langen psychedelischen Rauschtrack &#8222;Noit Aidar Oidar&#8220;, der eine v\u00f6llig andere Seite der Band zeigt. Zudem k\u00fcndigt Ivan an, dass die geplante LP in einer ver\u00e4nderten Besetzung aufgenommen wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Matthias Bosenick (27.11.2024) Hier ist sie nun also, die angek\u00fcndigte EP zur 7\u201c mit demselben Titel, \u201eRadio Radiation\u201c, des von Berlin aus agierenden Quartetts Sacred Buzz. Die beiden Vinyl-Tracks sind mit drauf, dazu vier neue, die sich allesamt in &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/sacred-buzz-radio-radiation-ep-fuzzed-up-astromoon-records-2024\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,8],"tags":[],"class_list":["post-7015","post","type-post","status-publish","format-standard","hentry","category-download-stream","category-maxi-cd-ep"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=7015"}],"version-history":[{"count":2,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7015\/revisions"}],"predecessor-version":[{"id":7033,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/7015\/revisions\/7033"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=7015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=7015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=7015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}