{"id":6389,"date":"2024-05-29T21:08:59","date_gmt":"2024-05-29T19:08:59","guid":{"rendered":"https:\/\/vanbauseneick.de\/krautnick\/?p=6389"},"modified":"2024-05-29T21:08:59","modified_gmt":"2024-05-29T19:08:59","slug":"was-meine-freundin-gerne-sieht-die-serienkolumne-schwarzbach-23-indiana-jones-aus-bayern","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/was-meine-freundin-gerne-sieht-die-serienkolumne-schwarzbach-23-indiana-jones-aus-bayern\/","title":{"rendered":"Was meine Freundin gerne sieht \u2013 die Serienkolumne: Schwarzbach 23 \u2013 Indiana Jones aus Bayern"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2022\/10\/Was-meine-Freundin-gerne-Logo-111.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2022\/10\/Was-meine-Freundin-gerne-Logo-111.jpg\" alt=\"\" class=\"wp-image-4578\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Von Onkel Rosebud<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meine Freundin zahlt gern GEZ-Geb\u00fchren f\u00fcr ein Krimi-Format, wo nach f\u00fcnf Minuten Handlung ein blinder Passagier aus Syrien aus einem Flugzeug vom Himmel auf einen Nazi mit derb Chemnitz-s\u00e4chsischen Akzent f\u00e4llt. Der Nazi stirbt daraufhin nicht, sondern wird im Laufe der Reha vom Faschisten zum Kronzeugen gel\u00e4utert und tr\u00e4gt zur L\u00f6sung des Falles bei. Klingt absurd, ist aber passiert. Am 22. Oktober 2016 pr\u00e4mierte im ZDF \u201eSchwarzach 23 und die Jagd nach dem Mordsfinger\u201c, Folge zwei der \u201eSchwarzbach 23\u201c-Reihe. Die anderen Folgen hei\u00dfen: \u201e\u2026und die Hand des Todes\u201c, \u201e&#8230;und der Sch\u00e4del des Saatans\u201c sowie \u201e\u2026und das m\u00f6rderische Ich\u201c. Indiana Jones w\u00fcrde sich im Grabe rumdrehen, wenn er schon drin liegen w\u00fcrde.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Leider wurde der offensichtlich nicht geb\u00fchrenfinanzierte Einheitsbrei nach vier Filmen eingestellt. An der Quote kann es nicht gelegen haben und an schlechten Kritiken auch nicht. Vom ZDF-Politb\u00fcro war folgendes zum Absetzen der Serie zu lesen: \u201e\u2026 die Reihe sei in ihrem Mix aus Krimi-Spannung und schwarzem Humor, aus dunklem Thrill und unterhaltsamem Familienzwist eine gelungene Auff\u00e4lligkeit in der ZDF-Primetime. Wir wollen bei einer Vielzahl an Reihen weiterhin die M\u00f6glichkeit zu haben, beweglich zu sein, Neues auszuprobieren und uns in unserem Gesamtportfolio weiterzuentwickeln.\u201c Mon Dieu, wie miefig und piefig. Die Message ist: Schwarzer Humor mit schr\u00e4gen und anarchischen Elementen wird nicht geb\u00fchrenfinanziert. Ein Krimi-Kom\u00f6die-Familienfilm, in dem ein Menschenkopf auf eine Vogelscheuche aufspie\u00dft wird, ist dem ZDF-Samstagskrimi-Publikum offenbar nicht zumutbar. Was f\u00fcr eine Fehleinsch\u00e4tzung. \u201eUnd jetzt pass auf\u201c oder was w\u00fcrde die Wolf Haas\u2018 Romanfigur Simon Brenner (gespielt von der jetzt schon Legende Josef Hader) dazu sagen: \u201eDas ist ja beim Menschen ein interessanter Widerspruch. Den Mut bewundert man, aber die Bl\u00f6dheit bewundert man nicht, obwohl es doch dasselbe ist.\u201d (aus \u201eM\u00fcll\u201c, Hoffmann und Campe, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Regisseur Matthias Tiefenbacher, ein geistiger Coen-Bruder, und seinem Hauptdarsteller Maximilian Br\u00fcckner als grantig-grummeligen Hauptkommissar Franz Germinger junior sei hiermit ein gro\u00dfes Lob ausgesprochen. Derb-ironischer Witz aus der bayerischen Provinz ist in der Mini-Reihe gl\u00e4nzend umgesetzt. Die Handlungen sind jeweils flott gewoben. Die Besetzung ist bis in die Nebenrollen hinein ausgezeichnet. Chapeau f\u00fcr Schwarzbach 23.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber, \u201ejetzt ist scho wieder was passiert\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Onkel Rosebud<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Onkel Rosebud Meine Freundin zahlt gern GEZ-Geb\u00fchren f\u00fcr ein Krimi-Format, wo nach f\u00fcnf Minuten Handlung ein blinder Passagier aus Syrien aus einem Flugzeug vom Himmel auf einen Nazi mit derb Chemnitz-s\u00e4chsischen Akzent f\u00e4llt. Der Nazi stirbt daraufhin nicht, sondern &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/was-meine-freundin-gerne-sieht-die-serienkolumne-schwarzbach-23-indiana-jones-aus-bayern\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,27],"tags":[],"class_list":["post-6389","post","type-post","status-publish","format-standard","hentry","category-tv","category-wasmeinefreundingerne"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/6389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=6389"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/6389\/revisions"}],"predecessor-version":[{"id":6390,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/6389\/revisions\/6390"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=6389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=6389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=6389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}