{"id":6251,"date":"2024-03-28T15:59:55","date_gmt":"2024-03-28T14:59:55","guid":{"rendered":"http:\/\/vanbauseneick.de\/krautnick\/?p=6251"},"modified":"2024-03-28T15:59:55","modified_gmt":"2024-03-28T14:59:55","slug":"tanks-and-tears-timewave-swiss-dark-nights-2024","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/tanks-and-tears-timewave-swiss-dark-nights-2024\/","title":{"rendered":"Tanks And Tears \u2013 Timewave \u2013 Swiss Dark Nights 2024"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/03\/Tanks-And-Tears-Timewave.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2024\/03\/Tanks-And-Tears-Timewave.jpg\" alt=\"\" class=\"wp-image-6252\"\/><\/a><\/figure>\n<\/div>\n\n\n<p>Von Matthias Bosenick (28.03.2024)<br><br>Diese \u201eTimewave\u201c reicht 40 Jahre zur\u00fcck: Sieben Jahre nach dem Deb\u00fct-Album \u201eAware\u201c reicht die zwischendurch zum Quartett angewachsene Band aus Prato bei Florenz ihr zweites Album nach. Ver\u00e4nderungen gab es nicht nur durch den Zuwachs eines Keyboarders, auch durch die weltweit bekannte Einschr\u00e4nkung bei der Entstehung des Albums: Corona zwang die vier zum Homerecording und digitalen Zusammenf\u00fchren der Files. Damit macht die Band einen erheblichen Schritt weg von Waverock und Postpunk zu Synthiepop und Indie-Electro der Achtziger. Selbst das Instrumentarium ist authentisch, daher ist die Platte so retro, als w\u00e4re sie bereits 40 Jahre alt. Mit ihren guten Songs rechtfertigen Tanks And Tears diesen R\u00fcckgriff \u2013 \u201eTimewave\u201c versetzt die H\u00f6renden zur\u00fcck in die dunklen Ecken der Achtziger.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Auch wenn das Keyboard und der Synthie \u2013 Roland SH-101 listet die Info exemplarisch auf, dazu Drummachines wie Roland TR-707, Linn und Korg DDD-5 \u2013 hier den Sound dominieren, vergessen Tanks And Tears nicht, dass sie auch noch Gitarre, Bass und Schlagzeug in ihren Heimstudios herumstehen haben. Diese setzen sie ein, wie es vor 40 Jahren die Bands aus Wave, Synthiepop, Electro und so vormachten, um daraus raumgreifende und dunkel gesungene Songs zu gestalten. Referenzen fallen einem beim H\u00f6ren von \u201eTimewave\u201c derart viele ein, dass man sie kaum benennen kann: DAF, Joy Division, Visage, alte Human League, Jan Hammer, The Neon Judgement, A Flock Of Seagulls, Martha And The Muffins bis hin zu sp\u00e4teren Nachahmern wie Editors. Tanks And Tears selbst listen noch andere Einfl\u00fcsse auf: die fr\u00fchen elektronischen Ministry, Nitzer Ebb, Cabaret Voltaire, Clock DVA, Bauhaus, Skinny Puppy und nat\u00fcrlich Depeche Mode. Kurios: Den klassischen Italo-Pop, den man hier erwarten w\u00fcrde, h\u00f6rt man nur bedingt heraus; typisch Achtziger ist es auch auf anderem Wege, auf einem d\u00fcstereren n\u00e4mlich.<br><br>Zwar sind auch Tanks And Tears in ihrer Grundf\u00e4rbung dunkel gehalten, doch \u00fcbernehmen sie von ausgew\u00e4hlten genannten Beispielen nicht das B\u00f6se, das Aggressive. Programmierte Basspatterns, fl\u00e4chige Synthiemelodien, dezidierte Effekte, tanzbare Rhythmen, es ist alles drin und in jedem Song anders. Das Titellied etwa ist eine Uptempo-Nummer mit Achtelbass und Electro-Snare-Claps, die man sich sowohl 1983 im Radio als auch heute im Gruftclub vorstellen kann, die erste H\u00e4lfte von \u201eDarkside\u201c k\u00f6nnte man mit dem sprunghaften Basslauf und den Keyboardfl\u00e4chen irgendwo bei \u201eSpeak And Spell\u201c von Depeche Mode einsortieren, \u201eHaze Of Lies\u201c ist die kraftvolle Electropo-Ballade des Albums, \u201eGalaxies\u201c hat mit der Flanger-Gitarre den Fu\u00df in der Wave-T\u00fcr, \u201eVampire Bite\u201c bettet elektronische Sounds wie bei The Normal in den Wavepop ein. Sehr abwechslungsreich, sehr retro; eine Produktionsweise von heute findet hier nicht statt, etwa durch moderne Beats oder abstraktere Strukturen. \u201eTimewave\u201c ist eine Zeitreise, die ihre Daseinsberechtigung dadurch erh\u00e4lt, dass die Songs zwar Erinnerungen wecken, aber komplett eigen sind.<br><br>Neu im Team ist Keyboarder Lorenzo Cantini, der wohl den Sound mit seinem Extra-Instrument zus\u00e4tzlich ins Synthetische zu schieben half. Denn Keyboards gab\u2019s bereits bei Tanks And Tears: S\u00e4nger und Bassist Matteo Cecchi spielt sie, Gitarrist Claudio Pinelli ebenfalls. Lediglich Francesco Ciulli blieb ausschlie\u00dflich bei seinem Schlagzeug. Jener trat der Gr\u00fcndungsformation erst ein Jahr sp\u00e4ter bei, also vor zehn Jahren, war mithin an s\u00e4mtlichen Aufnahmen ab der 2015er Deb\u00fct-EP \u201eKnow Yorself\u201c beteiligt. Was auf \u201eTimewave\u201c \u00fcbrigens fehlt, ist \u201eWaltz Of The Shadows\u201c, die B-Seite der Single \u201eNightmare\u201c, die die Band bereits 2022 ver\u00f6ffentlichte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Matthias Bosenick (28.03.2024) Diese \u201eTimewave\u201c reicht 40 Jahre zur\u00fcck: Sieben Jahre nach dem Deb\u00fct-Album \u201eAware\u201c reicht die zwischendurch zum Quartett angewachsene Band aus Prato bei Florenz ihr zweites Album nach. Ver\u00e4nderungen gab es nicht nur durch den Zuwachs eines &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/tanks-and-tears-timewave-swiss-dark-nights-2024\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6251","post","type-post","status-publish","format-standard","hentry","category-album"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/6251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=6251"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/6251\/revisions"}],"predecessor-version":[{"id":6253,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/6251\/revisions\/6253"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=6251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=6251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=6251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}