{"id":5793,"date":"2023-11-29T19:26:57","date_gmt":"2023-11-29T18:26:57","guid":{"rendered":"http:\/\/vanbauseneick.de\/krautnick\/?p=5793"},"modified":"2023-11-29T19:26:57","modified_gmt":"2023-11-29T18:26:57","slug":"was-meine-freundin-gerne-hoert-die-musikkolumne-epic-fails-musikwuensche-an-den-dj-folge-2","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/was-meine-freundin-gerne-hoert-die-musikkolumne-epic-fails-musikwuensche-an-den-dj-folge-2\/","title":{"rendered":"Was meine Freundin gerne h\u00f6rt \u2013 die Musikkolumne: Epic-Fails \u2013 Musikw\u00fcnsche an den DJ \u2013 Folge 2"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2022\/10\/Was-meine-Freundin-gerne-Logo-111.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2022\/10\/Was-meine-Freundin-gerne-Logo-111.jpg\" alt=\"\" class=\"wp-image-4578\"\/><\/a><\/figure>\n<\/div>\n\n\n<p>Von Onkel Rosebud<\/p>\n\n\n\n<p>Das Buch \u201eplus minus acht. DJ Tage, DJ N\u00e4chte\u201c (Kiepenheuer &amp; Witsch, 2003) des grundsympathischen Oberlippenbartr\u00e4gers Hans Nieswandt aus Mannheim ist ein Standardwerk der DJ-Techno\/House\/Disco-Culture der 80er\/90er Jahre. Darin gibt es ein Kapitel zum Thema H\u00f6rerw\u00fcnsche, welches ich als genre\u00fcbergreifender Plattenaufleger auch h\u00e4tte so schreiben k\u00f6nnen. Dieser Text ist 20 Jahre sp\u00e4ter eine Aktualisierung mit meinen Erfahrungen. Ein Remix sozusagen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Es gibt verschiedene Ph\u00e4notypen des Musikw\u00fcnschens an den DJ. Der Typ, den es bis heute immer noch gibt, ist der banale Ignorant. Er ignoriert einfach den Fakt, dass der DJ ein gewisses Programm verfolgt und ein Rahmen existiert und w\u00fcnscht sich einfach, was ihm privat gef\u00e4llt, zum Beispiel Helene Fischer oder Linkin Park. Der h\u00e4ufig angetrunkene Mensch fordert, dass es generell \u201eh\u00e4rter\u201c und \u201eschneller\u201c im DJ-Set zugehen sollte. Da ich dann so tue, als ob ich ihn nicht verstehen kann, weil die Musik zu laut ist, w\u00fcnscht er sich meist \u2013 schon im Abgang begriffen \u2013 \u201ewei\u00df auch nicht, ganz andere Musik\u201c oder \u201enormale Hits\u201c.<\/p>\n\n\n\n<p>Unangenehmer sind die Kandidaten, die sich bereits mehrere Alternativen zurechtgelgt haben oder erst anfangen, \u00fcber den Musikwunsch nachzudenken, wenn sie meine Aufmerksamkeit haben. Dialoge, die ich in diesem Kontext f\u00fcr die Ewigkeit gef\u00fchrt habe, gehen ungef\u00e4hr so: \u201eKannst Du Baba, baba hazam halum gelum daza spielen?\u201c \u2013 \u201eMeinst du Electrica Salsa von OFF?\u201c \u2013 \u201eJaja, genau.\u201c \u2013 \u201eAber das l\u00e4uft doch gerade.\u201c\u2026<\/p>\n\n\n\n<p>Manchmal geht es beim Musikw\u00fcnschen gar nicht um den Wunsch an sich. W\u00fcnsche k\u00f6nnen auch ein Vorwand sein, um mit dem DJ privat ins Gespr\u00e4ch zu kommen. Ihn mit Fachwissen zu beeindrucken. Subtil vorgetragen geht es dann bei haupts\u00e4chlich m\u00e4nnlichen Mitmenschen meistens darum, auch einfach mal f\u00fcr eine halbe Stunde die \u201eplus minus acht\u201c-Pitch-Control-Funktion am Plattenspieler bedienen zu d\u00fcrfen. Entsetzlich sind die entt\u00e4uschten Augen, wenn man mitteilen muss, Die Toten Hosen mit \u201eTage wie diese\u201c leider nicht dabei zu haben. Verst\u00e4ndnislose Blicke, dass man dem Geburtskind auch nicht mit \u201eHappy Birthday\u201c von Mariah Carey oder \u201eStairway To Heaven\u201c eine Freude machen kann. Der Zuruf \u201eDu hast ja gar nichts\u201c ist deshalb der ultimative Ritterschlag, den man w\u00e4hrend eines Sets entgegen geschleudert bekommen kann.<\/p>\n\n\n\n<p>Es gibt aber auch Momente, wo dem DJ nichts Gescheites einf\u00e4llt, und der Musikwunsch bringt die L\u00f6sung f\u00fcr das n\u00e4chste Lied, auch wenn nur noch 30 Sekunden bleiben, bis der n\u00e4chste Song loslegen muss. Denn es gibt sie immer, die Partyteilnehmerinnen mit dem Gesp\u00fcr f\u00fcr den Flow des Abends und der besseren Idee als die, die man selbst hat. Gerade, wenn man wie ich zwischen den Musikstilen herumjongliert, ist ein Hinweis wie \u201eJetzt Sofi Tucker w\u00e4re mega\u201c oder \u201eBester Zeitpunkt f\u00fcr Pisse oder Team Scheisse \u2013 ohne die kannst Du eh nicht nach Hause gehen\u201c oder \u201ewenn Du jetzt noch Jimi Tenor mit \u201aTake Me Baby\u2018 auspackst\u201c \u2026 das sind dann die Momente, wo ich nicht in einer von innen abschlie\u00dfbaren DJ-Box abenden will.<\/p>\n\n\n\n<p>Ich besitze ein (nat\u00fcrlich schwarzes) T-Shirt mit der Aufschrift \u201eI\u2019m not a Jukebox, I\u2019m a DJ\u201d. Was nichts anderes bedeutet, als dass Musikw\u00fcnsche quasi verboten sind. Es gibt nur eine Ausnahme zu der Regel: Der\/die W\u00fcnschende hat offensichtlich eine gute Zeit und kennt mich pers\u00f6nlich. Dann lege ich sogar Linkin Park auf, aber niemals Frau F.<\/p>\n\n\n\n<p>Onkel Rosebud<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Onkel Rosebud Das Buch \u201eplus minus acht. DJ Tage, DJ N\u00e4chte\u201c (Kiepenheuer &amp; Witsch, 2003) des grundsympathischen Oberlippenbartr\u00e4gers Hans Nieswandt aus Mannheim ist ein Standardwerk der DJ-Techno\/House\/Disco-Culture der 80er\/90er Jahre. Darin gibt es ein Kapitel zum Thema H\u00f6rerw\u00fcnsche, welches &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/was-meine-freundin-gerne-hoert-die-musikkolumne-epic-fails-musikwuensche-an-den-dj-folge-2\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,27],"tags":[],"class_list":["post-5793","post","type-post","status-publish","format-standard","hentry","category-buch","category-wasmeinefreundingerne"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=5793"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5793\/revisions"}],"predecessor-version":[{"id":5794,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5793\/revisions\/5794"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=5793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=5793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=5793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}