{"id":5507,"date":"2023-08-15T22:40:36","date_gmt":"2023-08-15T20:40:36","guid":{"rendered":"http:\/\/vanbauseneick.de\/krautnick\/?p=5507"},"modified":"2023-08-15T22:40:36","modified_gmt":"2023-08-15T20:40:36","slug":"araf-bathrah-antibody-2023","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/araf-bathrah-antibody-2023\/","title":{"rendered":"Araf \u2013 Bathrah \u2013 Antibody 2023"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2023\/08\/Araf-Bathrah.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2023\/08\/Araf-Bathrah.jpg\" alt=\"\" class=\"wp-image-5508\"\/><\/a><\/figure>\n<\/div>\n\n\n<p>Von Matthias Bosenick (15.08.2023)<br><br>Der Sound der EP \u201eBathrah\u201c ist nahe dem fr\u00fchen Wave, also synthetische Drums und introvertiert gegniedelte Gitarre, aber da es das ja schon seit 40 Jahren gibt, das Duo Araf da aber trotzdem etwas Eigenes draus stricken will, kombiniert es diese Musik mit der aus dem Nahen Osten und Westarabien. Othman Cherradi (alias Proph\u00e4n, Marokko) und Joseph Jadam (alias Maltash, Libanon) halten den Gesang der vier St\u00fccke ihrer in Br\u00fcssel aufgenommenen EP auf Arabisch, der Musik dazu gelingt der Spagat zwischen fr\u00fcher und heute, zwischen Europa und Arabien, zwischen Gothic und Folklore, ohne dass irgendetwas davon merkw\u00fcrdig wirkt. Aber daf\u00fcr angenehm deprimierend.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Der Drumcomputer pluckert stoisch vor sich hin, die Gitarre bleibt auf wenige T\u00f6ne beschr\u00e4nkt und gniedelt in hohen Tonlagen, so kennt man es, Red Lorry Yellow Lorry, The Sisters Of Mercy, ganz fr\u00fche The Cure, um nur die prominenteren Vertreter aufzulisten. Der dritte Track erf\u00fcllt die Erwartungen an das fr\u00fche Darkwave-Genre mit den wenigsten unerwarteten Elementen, das St\u00fcck h\u00e4tte musikalisch auch von \u2013 sagen wir \u2013 Screams For Tina sein k\u00f6nnen. Der Gesang murmelt monoton, wie gepresst, lauernd; ja, so kennt man das. Auch der vierte Song klingt noch vertraut, mit einer sch\u00f6nen Keyboardfl\u00e4che zu Gniedelgitarre, vertr\u00e4umt groovendem Bass und einem dem Industrial entnommenen Snare-Sound sowie ordentlich Hall auf der dunklen Stimme.<br><br>Anders die erste H\u00e4lfte der EP: Zwar startet der Opener mit einem typischen elektronischen Sound, doch sobald die Gitarre einsetzt, f\u00fchlt man sich in den Orient versetzt. Die Melodie tr\u00e4gt die arabische Folklore in den Song, der Sprechstimme ist deutlich das Arabische zu entnehmen, auch der Gesang orientiert sich an arabischer Melodik. Kombiniert mit Sisters-\u00e4hnlicher Musik ist der Song ein ungew\u00f6hnlicher Einstieg ins die grenzensprengende Gruftmucke, den auch der zweite Track aufgreift. Die Grundmusik ist weiterhin synthetisch, die Gitarre bleibt orientalisch, der Gesang schlie\u00dft sich dem dieses Mal an. Der ganze Track bekommt mehr Soundschichten, dies d\u00fcrfte der dichteste, hypnotischste dieser EP sein.<br><br>Nachdem Cherradi und Jadam bereits live zusammen auf B\u00fchnen standen, ist \u201eBathrah\u201c ihre erste gemeinsame Arbeit, die sie von Br\u00fcssel aus angehen. Sieht man sich die Logos ihrer jeweiligen Projekte Proph\u00e4n und Maltash an, k\u00e4me man eher auf den Gedanken, es mit Black Metal zu tun zu haben, und so ganz unrichtig ist das auch nicht: Maltash kombiniert Doom und Industrial mit orientalischen Einfl\u00fcssen, w\u00e4hrend Proph\u00e4n elektronische Industrial-Ritual-Musik macht. Beide \u00e4u\u00dfern sich jeweils politisch, zu gesellschaftlichen und religi\u00f6sen Missst\u00e4nden, da ist davon auszugehen, dass das auch auf \u201eBathrah\u201c zutrifft. Laut Info bedeutet der Titel \u201eEkel\u201c, wenngleich die virtuellen \u00dcbersetzer da andere Ergebnisse liefern, obschon die \u00dcbersetzung aus dem latinisierten Wort noch schwieriger sein d\u00fcrfte als direkt aus dem Arabischen. F\u00fcr den Projektnamen Araf gibt es die Vorschl\u00e4ge \u201eWahrsagerin\u201c und \u201eFegefeuer\u201c, er k\u00f6nnte auch an al-A\u2019raf angelehnt sein, die siebte Sure des Korans; f\u00fcr den Titel \u201eBathrah\u201c hei\u00dft es wahlweise \u201eBereichern Sie ihn\u201c, \u201ePickel\u201c oder \u201ePfui\u201c, was dem \u201eEkel\u201c am n\u00e4chsten k\u00e4me.<br><br>Die Tracks der EP mit versuchter \u00dcbersetzung aus mehreren Quellen:<br><br>01 \u201e\u0647\u0627\u0643 \u0648\u0627\u0631\u0627\u201c, \u201eHak wara\u201c, \u201eHier ist Wara\u201c<br>02 \u201e\u0639\u0644\u0649 \u062d\u064a\u0627\u062a\u064a\u201c, \u201eIn meinem Leben\u201c, andere Quelle: \u201e\u00dcber meine Leiche\u201c<br>03 \u201e\u0645\u0634 \u0639\u0627\u0631\u0641 \u062d\u0627\u0644\u064a\u201c, \u201eIch wei\u00df es jetzt nicht\u201c, andere Quelle: \u201eIch wei\u00df nicht, wie es mir geht\u201c<br>04 \u201e\u0645\u0628\u063a\u064a\u062a\u0634 \u0646\u0645\u0634\u064a\u201c, \u201eIch will nicht laufen\/gehen\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Matthias Bosenick (15.08.2023) Der Sound der EP \u201eBathrah\u201c ist nahe dem fr\u00fchen Wave, also synthetische Drums und introvertiert gegniedelte Gitarre, aber da es das ja schon seit 40 Jahren gibt, das Duo Araf da aber trotzdem etwas Eigenes draus &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/araf-bathrah-antibody-2023\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-5507","post","type-post","status-publish","format-standard","hentry","category-download-stream"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=5507"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5507\/revisions"}],"predecessor-version":[{"id":5509,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5507\/revisions\/5509"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=5507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=5507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=5507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}