{"id":5497,"date":"2023-08-13T20:50:35","date_gmt":"2023-08-13T18:50:35","guid":{"rendered":"http:\/\/vanbauseneick.de\/krautnick\/?p=5497"},"modified":"2023-08-14T23:02:21","modified_gmt":"2023-08-14T21:02:21","slug":"nuclear-power-trio-wet-ass-plutionium-metalblade-records-2023","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/nuclear-power-trio-wet-ass-plutionium-metalblade-records-2023\/","title":{"rendered":"Nuclear Power Trio \u2013 Wet Ass Plutonium \u2013 Metalblade Records 2023"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2023\/08\/Nuclear-Power-Trio-Wet-Ass-Plutionium.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2023\/08\/Nuclear-Power-Trio-Wet-Ass-Plutionium.jpg\" alt=\"\" class=\"wp-image-5498\"\/><\/a><\/figure>\n<\/div>\n\n\n<p>Von Guido D\u00f6rheide (11.08.2023)<\/p>\n\n\n\n<p>Alle Welt sucht nach nachhaltigen Energien, die zudem noch sexy sein sollten. Mit Donnie, Vlad und Kim, dem Nuclear Power Trio, gibt es das nun endlich. Auf dem Cover von \u201eWet Ass Plutonium\u201c (ja richtig \u2013 das spielt auf Cardi B\u2019s \u201eWAP\u201c aus 2020 an) sehen wir die drei Musikanten sehr h\u00fcbsch vor, auf und in einem Lamborghini Countach aus den 80ern drapiert, und an Nuclear Power kann nun ja auch wirklich nichts verkehrt sein. Wer nun gespannt ist auf die Texte des Trios, der kann beruhigt aufatmen: \u201eWet Ass Plutonium\u201c ist, wie schon sein Vorg\u00e4nger, die 2020er EP \u201eA Clear And Present Rager\u201c, ein reines Instrumentalwerk. Und was f\u00fcr eins!<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Donnie (Greg Burgess an der Gitarre, unter anderem bekannt von Allegaeon), Vlad (Nick Schendzielos am Bass, sonst bei Havok) und Kim (Pete Webber, Drummer von Havok) verstehen ihr Handwerk, beherrschen ihre Instrumente, wissen, was sie tun, und haben dabei immer den Schalk im Nacken. Letzteren \u00fcbrigens tats\u00e4chlich haupts\u00e4chlich bei der Titelvergabe: \u201eWet Ass Plutonium\u201c, \u201eApocalypse Mao\u201c, \u201eNyetflix And Chill\u201c, \u201eSnark Side Of The Un\u201cund \u201eCritical Bass Theory\u201c sprechen eine Sprache, die sowohl Schnappatmung als auch spontane hemmungslose Lachsalven hervorruft, jenseits davon ist die Musik einerseits hochgradig unterhaltend und andererseits ob ihrer Virtuosit\u00e4t bewundernswert. Wo ich gerade bei den Songtiteln bin: Schon die Erstlings-EP \u201eA Clear And Present Rager\u201c wartete mit Schmankerln wie \u201eGrab \u2018em By The Pyongyang\u201c und \u201eUkraine In The Membrane\u201c (und das noch vor dem Krieg!) auf.<\/p>\n\n\n\n<p>Musikalisch w\u00fcrde ich das Nuclear Power Trio erstmal beim Prog einordnen, beeinflusst von viel Thrash, aber viel viel zu frickelig, um komplett dort verortet zu werden. Am Bass wird viel geslappt und funky gegroovet, zwischendurch gibt es viel Lateinamerikanisches zu h\u00f6ren, und immer, wenn man sich da sch\u00f6n reingezappelt hat, donnert auf einmal die Gitarre um einiges h\u00e4rter und von einem wuchtigen Schlagzeug befeuert los, also doch wieder irgendwie Thrash. Zwischendurch gibt es Synthies zu h\u00f6ren, die dem Gesamtsound des Trios keine Cheesigkeit verleihen, sondern ihrerseits mit nach vorne gehen.<\/p>\n\n\n\n<p>Fazit: Es braucht keinen Gesang, um progressiven Metal zu machen, der technisch anspruchsvoll ist, genre\u00fcbergeifend die Amerikas \u00fcberspannt und beim H\u00f6ren unheimlich viel gute Laune macht.<\/p>\n\n\n\n<p>Am Ende einige Anspieltipps:<\/p>\n\n\n\n<p>#2: \u201eApocalypse Mao\u201c: W\u00e4hrend der Opener \u201eW.A.P\u201c noch eher konventionellen Metal mit maximalem Fun-Faktor brachte, springt der zweite Song munter zwischen sprunghaftem Bass-Geslappe und vertr\u00e4umten Gitarrenmelodien her und macht neugierig auf das, was nun noch kommen mag.<\/p>\n\n\n\n<p>#3: \u201eNyetflix And Chill\u201c: Hier wird es nun zum ersten mal lateinamerikanisch: Zur Metal-Trinit\u00e4t aus Gitarre, Bass und Schlagzeug gesellen sich haufenweise Bl\u00e4ser und lassen Gloria Estefan und die Miami Sound Machine alt aussehen. Und \u2013 sorry, Gloria \u2013 zum Gl\u00fcck singt hier niemand.<\/p>\n\n\n\n<p>#6: \u201e\u00a1Vamos, Bandito!\u201c: Der Song beginnt mit einem lateinamerikanisch klapperndem Schlagzeug und einer ebensolchen Akustikgitarre, wie sie auch den Gipsy Kings gut zu Gesicht st\u00fcnde. Das zieht sich eine gute Minute so hin und dann kommt eine E-Gitarre hinzu, dann der funky Bass, das Schlagzeug macht stoisch weiter wie zu Anfang und den H\u00f6renden steigt ein Grinsen ins Gesicht, das so schnell nicht mehr weggeht.<\/p>\n\n\n\n<p>Auf #7 \u201eAnti-Saxxers (Mandatory Saxination)\u201c und #8 \u201eCritical Bass Theory\u201c gibt es dann wieder Bass, meine Damen und Herren, Bass!<\/p>\n\n\n\n<p>Wenn schon Metal ohne Gesang, dann jederzeit gerne wie hier vom Nuclear Power Trio dargeboten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Guido D\u00f6rheide (11.08.2023) Alle Welt sucht nach nachhaltigen Energien, die zudem noch sexy sein sollten. Mit Donnie, Vlad und Kim, dem Nuclear Power Trio, gibt es das nun endlich. Auf dem Cover von \u201eWet Ass Plutonium\u201c (ja richtig \u2013 &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/nuclear-power-trio-wet-ass-plutionium-metalblade-records-2023\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5497","post","type-post","status-publish","format-standard","hentry","category-album"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=5497"}],"version-history":[{"count":2,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5497\/revisions"}],"predecessor-version":[{"id":5503,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5497\/revisions\/5503"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=5497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=5497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=5497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}