{"id":5494,"date":"2023-08-11T15:57:13","date_gmt":"2023-08-11T13:57:13","guid":{"rendered":"http:\/\/vanbauseneick.de\/krautnick\/?p=5494"},"modified":"2023-08-11T15:57:13","modified_gmt":"2023-08-11T13:57:13","slug":"church-of-misery-born-under-a-mad-sign-rise-above-records-2023","status":"publish","type":"post","link":"https:\/\/vanbauseneick.de\/krautnick\/church-of-misery-born-under-a-mad-sign-rise-above-records-2023\/","title":{"rendered":"Church Of Misery \u2013 Born Under A Mad Sign \u2013 Rise Above Records 2023"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2023\/08\/Church-Of-Misery-Born-Under-A-Mad-Sign.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"111\" height=\"111\" src=\"http:\/\/vanbauseneick.de\/krautnick\/wp-content\/uploads\/2023\/08\/Church-Of-Misery-Born-Under-A-Mad-Sign.jpg\" alt=\"\" class=\"wp-image-5495\"\/><\/a><\/figure>\n<\/div>\n\n\n<p>Von Guido D\u00f6rheide (10.08.2023)<\/p>\n\n\n\n<p>Herzlich willkommen zu einer neuen Folge von \u201eHerr D\u00f6rheide schlie\u00dft seine Bildungsl\u00fccken\u201c. Ich frage mich, warum ich von Church Of Misery, einer seit \u00fcber 30 Jahren aktiven Stoner\/Doom-\/Sludge-Metal-Band aus Tokio, die sich dem Thema \u201eSerienm\u00f6rder\u201c verschrieben hat, noch nie etwas geh\u00f6rt habe. Als ich erstmals des Cover-Artworks von \u201eBorn Under A Mad Sign\u201c angesichtig wurde, d\u00e4mmerte mir bereits, dass ich es hier mit einer eventuell \u00fcberaus schlie\u00dfenswerten Bildungsl\u00fccke zu tun habe: Das Cover ist im Stil von Blue Note Records aufgebaut, ganz in Blau- und Schwarzt\u00f6nen gehalten (gibt es \u00fcberhaupt unterschiedliche Schwarzt\u00f6ne? Oder einfach nur Schwarz?) und besteht au\u00dfer Text aus dem Foto eines Mannes mit Hut, der den Betrachter nicht unfreundlich anblickt. War weiland bei Blue Note vorwiegend der auf dem Album spielende Musiker nebst Instrument zu sehen, ist es hier Fritz Haarmann aus Hannover, Niedersachsen, der den Betrachtenden anblickt. Auch der Titel machte mich neugierig, schlie\u00dflich ist \u201eBorn Under A Bad Sign\u201c von Albert King (einem der drei Kings of the Blues Guitar) eines meiner liebsten Bluesalben. Und es unterscheidet sich ja nur in einem Buchstaben von dem hier vorliegenden Werk.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>So viel sei vorweggenommen: Auf dem Album finden sich nichts von Albert King, daf\u00fcr aber ein ganzes St\u00fcck (\u201eMost Evil\u201c), das Haarmann gewidmet ist. Und was f\u00fcr eins: Knappe 10 Minuten lang t\u00fcrmen Bassist und Bandchef Tatsu Mikami und seine drei Mitmusikanten knarzige, analog klingende Riffs, hypnotische Rhythmen und herausgepresstes Gecroone eines S\u00e4ngers, der offensichtlich nicht nur die Melvins, sondern auch EyeHateGod gr\u00fcndlich studiert hat, aufeinander, Chef ihm sein Rickenbacker sorgt dabei f\u00fcr die ordentliche Portion Rock\u2019n\u2019Roll, die allerdings weniger h\u00f6r- als auf jeden Fall f\u00fchlbar ist. Bereits dieser Song (es ist Nummer zwei auf dem Album) macht mich hoffen, dass sich bei der Kirche des Elends Fans von Stonerdronedeathdoom nach der Art von Boris (ebenfalls aus Tokio) mehr abgeholt f\u00fchlen als solche von traditionellen skandinavischen Doombands wie sagen wir mal Candlemass.<\/p>\n\n\n\n<p>Und diese Hoffnung wird erf\u00fcllt: Bereits das Er\u00f6ffnungslied \u201eBeltway Sniper\u201c, das von John Allen Muhammad handelt, einem der Heckensch\u00fctzen vom Washington D.C. Beltway. und mit einem Auszug aus einer zeitgen\u00f6ssischen Nachrichtensendung beginnt und dann ein polterndes und drohendes Doom-Matal-Szenario aus einem alles verschlingenden Schlagzeug und einer langsam dr\u00f6hnenden Gitarre aufbaut, zu dem sich dann ein \u00fcberraschend hoher, rauher Gesang hinzugesellt, der angenehm songdienlich in den Hintergrund gemischt ist. Diese Band bratzt einem das, was sie drauf und zu sagen hat, nicht ins Gesicht, sondern agiert trotz aller Wucht und Energie eher subtil.<\/p>\n\n\n\n<p>Schon bei diesem ersten St\u00fcck w\u00fcnschte ich mir, die 8:43 Minuten w\u00fcrden nicht so schnell vor\u00fcbergehen. \u00dcberhaupt: Die Songs auf \u201eBorn Under A Mad Sign\u201c sind nicht eben kurz \u2013 das dritte St\u00fcck \u201eFreeway Madness Boogie\u201c (den mindestens 16fachen M\u00f6rder Randy Kraft abhandelnd) ist mit 6:06 Minuten das k\u00fcrzeste St\u00fcck des Albums. Auf diesem, trotz seiner vermeintlichen K\u00fcrze an ausgiebig rock\u2019n\u2019rolligen Instrumentalteilen nicht eben armen St\u00fcck kommt der heisere und inbr\u00fcnstig dargebotene Gesang von Kazuhiro Asaeda besonders gut zur Geltung. Das folgende \u201eMurder Castle Blues\u201c (hier geht es um H.H. Holmes, einen der ersten Serienm\u00f6rder der US of A) beginnt ruhig mit einem Bass und dem Schlagzeug, zu dem Bassriff gesellt sich dann eine zun\u00e4chst ruhige Gitarre, bis nach 50 Sekunden klargestellt wird, dass wir es hier mit einem klassischen Doom-Album zu tun haben. Alles klingt wieder sehr analog, kr\u00e4chzig und knarzend, allein Asaedas Gesang ist hier tiefer, voller und mehr im Stoner verhaftet. Der n\u00e4chste Song hei\u00dft \u201eSpoiler\u201c, \u00fcberrascht durch eine Orgel, zieht das Tempo ein wenig an und l\u00e4sst die guten Zeiten rocken und rollen. Monoton, repetitiv, orgelnd, rockend, rollend und stampfend, halt Japan, wie wir es uns immer vorgestellt haben.<\/p>\n\n\n\n<p>Hernach gibt es wieder einen Auszug aus einer Nachrichtensendung zu h\u00f6ren, dann treibt das Schlagzeug forsch voran, begleitet von einem verzerrten Bass, bis schlie\u00dflich auch die Gitarre einsetzt. \u201eCome And Get Me Sucker\u201c handelt von David Koresh, dem komplett bekloppten und skrupellosen Chef der Davidianer-Sekte, der 1993 im Zuge der mehrw\u00f6chigen Belagerung des Sektenhauptquartiers get\u00f6tet wurde. Der Song sorgt nach der Orgel des Vorg\u00e4ngers durch sein Tempo und seine Breaks wieder einmal mehr f\u00fcr Abwechslung, der Sound und der Gesang tragen gleichsam zur Wiedererkennbarkeit bei und lassen das Album wie aus einem Guss wirken, ohne jemals zu langweilen.<\/p>\n\n\n\n<p>Beim letzten Song schlie\u00dft sich dann der Kreis zu einem meiner berufsbedingten gr\u00f6\u00dften Kundenkreise, der Allgemeinen Luftfahrt: \u201eButcher Baker\u201c behandelt den Fall Robert C. Hansen, der seine Opfer mit seinem Privatflugzeug zum Tatort in Alaska flog und ihnen dort Unvorstellbares antat, um sie danach zu jagen und zu t\u00f6ten. Gemessen daran klingt die musikalische Umsetzung fast zahm, kennt man den Hintergrund, sorgt sie jedoch f\u00fcr G\u00e4nsehaut: Im Vordergrund donnernd-doomige Riffs mit viel Verzerrung, knapp dahinter raunend-gr\u00f6hlender Gesang, Church Of Misery erzeugen hier eine Stimmung, die \u2013 kennt man die Story dahinter \u2013 die Panik der Opfer explizit veranschaulicht. Und die H\u00f6renden gleicherma\u00dfen ver\u00e4ngstigt als auch begeistert zur\u00fcckl\u00e4sst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Guido D\u00f6rheide (10.08.2023) Herzlich willkommen zu einer neuen Folge von \u201eHerr D\u00f6rheide schlie\u00dft seine Bildungsl\u00fccken\u201c. Ich frage mich, warum ich von Church Of Misery, einer seit \u00fcber 30 Jahren aktiven Stoner\/Doom-\/Sludge-Metal-Band aus Tokio, die sich dem Thema \u201eSerienm\u00f6rder\u201c verschrieben &hellip; <a href=\"https:\/\/vanbauseneick.de\/krautnick\/church-of-misery-born-under-a-mad-sign-rise-above-records-2023\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5494","post","type-post","status-publish","format-standard","hentry","category-album"],"_links":{"self":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/comments?post=5494"}],"version-history":[{"count":1,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5494\/revisions"}],"predecessor-version":[{"id":5496,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/posts\/5494\/revisions\/5496"}],"wp:attachment":[{"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/media?parent=5494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/categories?post=5494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanbauseneick.de\/krautnick\/wp-json\/wp\/v2\/tags?post=5494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}